{"id":266,"count":2,"description":"","link":"https:\/\/generic.wordpress.soton.ac.uk\/southamptonconnects\/tag\/finance\/","name":"finance","slug":"finance","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>finance Archives - Hartley News Online<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/generic.wordpress.soton.ac.uk\/southamptonconnects\/tag\/finance\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"finance Archives - Hartley News Online\" \/>\n<meta property=\"og:url\" content=\"https:\/\/generic.wordpress.soton.ac.uk\/southamptonconnects\/tag\/finance\/\" \/>\n<meta property=\"og:site_name\" content=\"Hartley News Online\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/generic.wordpress.soton.ac.uk\\\/southamptonconnects\\\/tag\\\/finance\\\/\",\"url\":\"https:\\\/\\\/generic.wordpress.soton.ac.uk\\\/southamptonconnects\\\/tag\\\/finance\\\/\",\"name\":\"finance Archives - Hartley News Online\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/generic.wordpress.soton.ac.uk\\\/southamptonconnects\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/generic.wordpress.soton.ac.uk\\\/southamptonconnects\\\/tag\\\/finance\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/generic.wordpress.soton.ac.uk\\\/southamptonconnects\\\/tag\\\/finance\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"http:\\\/\\\/generic.wordpress.soton.ac.uk\\\/southamptonconnects\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"finance\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/generic.wordpress.soton.ac.uk\\\/southamptonconnects\\\/#website\",\"url\":\"http:\\\/\\\/generic.wordpress.soton.ac.uk\\\/southamptonconnects\\\/\",\"name\":\"Hartley News Online\",\"description\":\"University of Southampton\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/generic.wordpress.soton.ac.uk\\\/southamptonconnects\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"finance Archives - Hartley News Online","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/generic.wordpress.soton.ac.uk\/southamptonconnects\/tag\/finance\/","og_locale":"en_US","og_type":"article","og_title":"finance Archives - Hartley News Online","og_url":"https:\/\/generic.wordpress.soton.ac.uk\/southamptonconnects\/tag\/finance\/","og_site_name":"Hartley News Online","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/generic.wordpress.soton.ac.uk\/southamptonconnects\/tag\/finance\/","url":"https:\/\/generic.wordpress.soton.ac.uk\/southamptonconnects\/tag\/finance\/","name":"finance Archives - Hartley News Online","isPartOf":{"@id":"http:\/\/generic.wordpress.soton.ac.uk\/southamptonconnects\/#website"},"breadcrumb":{"@id":"https:\/\/generic.wordpress.soton.ac.uk\/southamptonconnects\/tag\/finance\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/generic.wordpress.soton.ac.uk\/southamptonconnects\/tag\/finance\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"http:\/\/generic.wordpress.soton.ac.uk\/southamptonconnects\/"},{"@type":"ListItem","position":2,"name":"finance"}]},{"@type":"WebSite","@id":"http:\/\/generic.wordpress.soton.ac.uk\/southamptonconnects\/#website","url":"http:\/\/generic.wordpress.soton.ac.uk\/southamptonconnects\/","name":"Hartley News Online","description":"University of Southampton","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/generic.wordpress.soton.ac.uk\/southamptonconnects\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/generic.wordpress.soton.ac.uk\/southamptonconnects\/wp-json\/wp\/v2\/tags\/266","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/generic.wordpress.soton.ac.uk\/southamptonconnects\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/generic.wordpress.soton.ac.uk\/southamptonconnects\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/generic.wordpress.soton.ac.uk\/southamptonconnects\/wp-json\/wp\/v2\/posts?tags=266"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}