{"id":22,"date":"2016-07-28T16:17:44","date_gmt":"2016-07-28T15:17:44","guid":{"rendered":"http:\/\/generic.wordpress.soton.ac.uk\/reech\/wp-content\/uploads\/sites\/141\/2016\/07\/peter-dawes-trophy.jpg"},"modified":"2016-07-28T16:17:44","modified_gmt":"2016-07-28T15:17:44","slug":"peter-dawes-trophy","status":"inherit","type":"attachment","link":"https:\/\/generic.wordpress.soton.ac.uk\/reech\/2016\/07\/27\/new-forest-show\/peter-dawes-trophy\/","title":{"rendered":"peter dawes trophy"},"author":1730,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"class_list":["post-22","attachment","type-attachment","status-inherit","hentry"],"smush":"Not processed","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/a7IKTM-m","jetpack_likes_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href=\"https:\/\/i0.wp.com\/generic.wordpress.soton.ac.uk\/reech\/wp-content\/uploads\/sites\/141\/2016\/07\/peter-dawes-trophy.jpg?ssl=1\"><img loading=\"lazy\" decoding=\"async\" width=\"225\" height=\"300\" src=\"https:\/\/i0.wp.com\/generic.wordpress.soton.ac.uk\/reech\/wp-content\/uploads\/sites\/141\/2016\/07\/peter-dawes-trophy.jpg?fit=225%2C300&amp;ssl=1\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/generic.wordpress.soton.ac.uk\/reech\/wp-content\/uploads\/sites\/141\/2016\/07\/peter-dawes-trophy.jpg?w=2448&amp;ssl=1 2448w, https:\/\/i0.wp.com\/generic.wordpress.soton.ac.uk\/reech\/wp-content\/uploads\/sites\/141\/2016\/07\/peter-dawes-trophy.jpg?resize=225%2C300&amp;ssl=1 225w, https:\/\/i0.wp.com\/generic.wordpress.soton.ac.uk\/reech\/wp-content\/uploads\/sites\/141\/2016\/07\/peter-dawes-trophy.jpg?resize=768%2C1024&amp;ssl=1 768w, https:\/\/i0.wp.com\/generic.wordpress.soton.ac.uk\/reech\/wp-content\/uploads\/sites\/141\/2016\/07\/peter-dawes-trophy.jpg?resize=700%2C933&amp;ssl=1 700w, https:\/\/i0.wp.com\/generic.wordpress.soton.ac.uk\/reech\/wp-content\/uploads\/sites\/141\/2016\/07\/peter-dawes-trophy.jpg?resize=332%2C443&amp;ssl=1 332w, https:\/\/i0.wp.com\/generic.wordpress.soton.ac.uk\/reech\/wp-content\/uploads\/sites\/141\/2016\/07\/peter-dawes-trophy.jpg?w=1510 1510w, https:\/\/i0.wp.com\/generic.wordpress.soton.ac.uk\/reech\/wp-content\/uploads\/sites\/141\/2016\/07\/peter-dawes-trophy.jpg?w=2265 2265w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" data-attachment-id=\"22\" data-permalink=\"https:\/\/generic.wordpress.soton.ac.uk\/reech\/2016\/07\/27\/new-forest-show\/peter-dawes-trophy\/\" data-orig-file=\"https:\/\/i0.wp.com\/generic.wordpress.soton.ac.uk\/reech\/wp-content\/uploads\/sites\/141\/2016\/07\/peter-dawes-trophy.jpg?fit=2448%2C3264&amp;ssl=1\" data-orig-size=\"2448,3264\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.2&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPhone 5s&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1469636320&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;4.15&quot;,&quot;iso&quot;:&quot;32&quot;,&quot;shutter_speed&quot;:&quot;0.0095238095238095&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"peter dawes trophy\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/generic.wordpress.soton.ac.uk\/reech\/wp-content\/uploads\/sites\/141\/2016\/07\/peter-dawes-trophy.jpg?fit=755%2C1007&amp;ssl=1\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":2448,"height":3264,"file":"2016\/07\/peter-dawes-trophy.jpg","sizes":{"thumbnail":{"file":"peter-dawes-trophy-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/generic.wordpress.soton.ac.uk\/reech\/wp-content\/uploads\/sites\/141\/2016\/07\/peter-dawes-trophy.jpg?resize=150%2C150&ssl=1"},"medium":{"file":"peter-dawes-trophy-225x300.jpg","width":225,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/generic.wordpress.soton.ac.uk\/reech\/wp-content\/uploads\/sites\/141\/2016\/07\/peter-dawes-trophy.jpg?fit=225%2C300&ssl=1"},"medium_large":{"file":"peter-dawes-trophy-768x1024.jpg","width":768,"height":1024,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/generic.wordpress.soton.ac.uk\/reech\/wp-content\/uploads\/sites\/141\/2016\/07\/peter-dawes-trophy.jpg?fit=755%2C1007&ssl=1"},"large":{"file":"peter-dawes-trophy-768x1024.jpg","width":768,"height":1024,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/generic.wordpress.soton.ac.uk\/reech\/wp-content\/uploads\/sites\/141\/2016\/07\/peter-dawes-trophy.jpg?fit=755%2C1007&ssl=1"},"sliderthumb":{"file":"peter-dawes-trophy-1140x250.jpg","width":1140,"height":250,"mime_type":"image\/jpeg","source_url":"https:\/\/generic.wordpress.soton.ac.uk\/reech\/wp-content\/uploads\/sites\/141\/2016\/07\/peter-dawes-trophy-1140x250.jpg"},"blog-thumb":{"file":"peter-dawes-trophy-700x933.jpg","width":700,"height":933,"mime_type":"image\/jpeg","source_url":"https:\/\/generic.wordpress.soton.ac.uk\/reech\/wp-content\/uploads\/sites\/141\/2016\/07\/peter-dawes-trophy-700x933.jpg"},"teaser-thumb":{"file":"peter-dawes-trophy-332x443.jpg","width":332,"height":443,"mime_type":"image\/jpeg","source_url":"https:\/\/generic.wordpress.soton.ac.uk\/reech\/wp-content\/uploads\/sites\/141\/2016\/07\/peter-dawes-trophy-332x443.jpg"},"gallery-1-thumb":{"file":"peter-dawes-trophy-432x432.jpg","width":432,"height":432,"mime_type":"image\/jpeg","source_url":"https:\/\/generic.wordpress.soton.ac.uk\/reech\/wp-content\/uploads\/sites\/141\/2016\/07\/peter-dawes-trophy-432x432.jpg"},"gallery-2-thumb":{"file":"peter-dawes-trophy-268x268.jpg","width":268,"height":268,"mime_type":"image\/jpeg","source_url":"https:\/\/generic.wordpress.soton.ac.uk\/reech\/wp-content\/uploads\/sites\/141\/2016\/07\/peter-dawes-trophy-268x268.jpg"},"gallery-3-thumb":{"file":"peter-dawes-trophy-268x164.jpg","width":268,"height":164,"mime_type":"image\/jpeg","source_url":"https:\/\/generic.wordpress.soton.ac.uk\/reech\/wp-content\/uploads\/sites\/141\/2016\/07\/peter-dawes-trophy-268x164.jpg"},"image-thumb":{"file":"peter-dawes-trophy-700x933.jpg","width":700,"height":933,"mime_type":"image\/jpeg","source_url":"https:\/\/generic.wordpress.soton.ac.uk\/reech\/wp-content\/uploads\/sites\/141\/2016\/07\/peter-dawes-trophy-700x933.jpg"},"video-thumb":{"file":"peter-dawes-trophy-700x393.jpg","width":700,"height":393,"mime_type":"image\/jpeg","source_url":"https:\/\/generic.wordpress.soton.ac.uk\/reech\/wp-content\/uploads\/sites\/141\/2016\/07\/peter-dawes-trophy-700x393.jpg"},"full":{"file":"peter-dawes-trophy.jpg?fit=2448%2C3264&ssl=1","width":2448,"height":3264,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/generic.wordpress.soton.ac.uk\/reech\/wp-content\/uploads\/sites\/141\/2016\/07\/peter-dawes-trophy.jpg?fit=2448%2C3264&ssl=1"}},"image_meta":{"aperture":"2.2","credit":"","camera":"iPhone 5s","caption":"","created_timestamp":"1469636320","copyright":"","focal_length":"4.15","iso":"32","shutter_speed":"0.0095238095238095","title":"","orientation":"1","keywords":[]}},"post":18,"source_url":"https:\/\/generic.wordpress.soton.ac.uk\/reech\/wp-content\/uploads\/sites\/141\/2016\/07\/peter-dawes-trophy.jpg","_links":{"self":[{"href":"https:\/\/generic.wordpress.soton.ac.uk\/reech\/wp-json\/wp\/v2\/media\/22","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/generic.wordpress.soton.ac.uk\/reech\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/generic.wordpress.soton.ac.uk\/reech\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/generic.wordpress.soton.ac.uk\/reech\/wp-json\/wp\/v2\/users\/1730"}],"replies":[{"embeddable":true,"href":"https:\/\/generic.wordpress.soton.ac.uk\/reech\/wp-json\/wp\/v2\/comments?post=22"}]}}